{"id":1074,"date":"2025-01-15T15:31:25","date_gmt":"2025-01-15T14:31:25","guid":{"rendered":"http:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970.jpeg"},"modified":"2025-01-15T15:31:25","modified_gmt":"2025-01-15T14:31:25","slug":"img_6970","status":"inherit","type":"attachment","link":"https:\/\/www.mirevaltrail.fr\/gardiole\/img_6970\/","title":{"rendered":"IMG_6970"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-300x200.jpeg 300w, https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":427,"file":"2025\/01\/IMG_6970.jpeg","filesize":209367,"sizes":{"medium":{"file":"IMG_6970-300x200.jpeg","width":300,"height":200,"filesize":26935,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-300x200.jpeg"},"thumbnail":{"file":"IMG_6970-150x150.jpeg","width":150,"height":150,"filesize":10860,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-150x150.jpeg"},"colormag-highlighted-post":{"file":"IMG_6970-392x272.jpeg","width":392,"height":272,"filesize":46742,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-392x272.jpeg"},"colormag-featured-post-medium":{"file":"IMG_6970-390x205.jpeg","width":390,"height":205,"filesize":37645,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-390x205.jpeg"},"colormag-featured-post-small":{"file":"IMG_6970-130x90.jpeg","width":130,"height":90,"filesize":6035,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-130x90.jpeg"},"meta-slider-resized-640x411":{"file":"IMG_6970-640x411.jpeg","width":640,"height":411,"filesize":121496,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-640x411.jpeg"},"meta-slider-resized-620x398":{"file":"IMG_6970-620x398.jpeg","width":620,"height":398,"filesize":104019,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-620x398.jpeg"},"meta-slider-resized-400x257":{"file":"IMG_6970-400x257.jpeg","width":400,"height":257,"filesize":45805,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970-400x257.jpeg"},"full":{"file":"IMG_6970.jpeg","width":640,"height":427,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-content\/uploads\/2025\/01\/IMG_6970.jpeg","_links":{"self":[{"href":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-json\/wp\/v2\/media\/1074"}],"collection":[{"href":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mirevaltrail.fr\/gardiole\/wp-json\/wp\/v2\/comments?post=1074"}]}}